{"id":20423,"date":"2019-05-21T11:21:25","date_gmt":"2019-05-21T09:21:25","guid":{"rendered":"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/?p=20423"},"modified":"2019-05-21T11:32:38","modified_gmt":"2019-05-21T09:32:38","slug":"ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute","status":"publish","type":"post","link":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/","title":{"rendered":"&#8211; Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute"},"content":{"rendered":"<h4>Rui Filipe Gutschmidt<\/h4>\n<h2><strong>Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute<\/strong><\/h2>\n<div id=\"attachment_8722\" style=\"width: 110px\" class=\"wp-caption alignleft\"><img aria-describedby=\"caption-attachment-8722\" loading=\"lazy\" class=\"size-full wp-image-8722\" src=\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2037\/12\/Rui_Gutschmidt.jpg\" alt=\"\" width=\"100\" height=\"150\" \/><p id=\"caption-attachment-8722\" class=\"wp-caption-text\"><span style=\"color: #808080;\">Rui Filipe Gutschmidt<\/span><\/p><\/div>\n<p style=\"text-align: justify;\"><b>Viele wollen den schnellen Klimawandel nicht wahrhaben oder den Einfluss des Menschen kleinreden. Es ist nicht weiter verwunderlich, denn die Rohstoff- und Energiemafia verdient Milliarden mit fossilen Brennstoffen. Aber auch das Abschmelzen der Eiskappe am Nordpol bringt neue Gewinnchancen f\u00fcr das Gro\u00dfkapital mit sich. Cui bono?<\/b><i><\/i><\/p>\n<p style=\"text-align: justify;\">Wer hat den Nutzen? Das ist eine Frage die man sich immer wieder stellen sollte, wenn es um die Wahrheitsfindung geht. Dabei sind nicht immer alle Profiteure auch Verursacher einer Situation. Aber kaum einer dieser Konzerne wird eine gute Gelegenheit verhindern wollen, wenn diese sich bietet.<\/p>\n<div id=\"attachment_20425\" style=\"width: 330px\" class=\"wp-caption alignright\"><img aria-describedby=\"caption-attachment-20425\" loading=\"lazy\" class=\" wp-image-20425\" src=\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2019\/05\/kuiz-300x184.jpg\" alt=\"\" width=\"320\" height=\"196\" srcset=\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2019\/05\/kuiz-300x184.jpg 300w, https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2019\/05\/kuiz.jpg 630w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><p id=\"caption-attachment-20425\" class=\"wp-caption-text\"><span style=\"color: #808080;\">Nordostpassage-NASA &#8211; Wikipedia Commons CC 0<\/span><\/p><\/div>\n<p style=\"text-align: justify;\">So ist es auch mit dem Nutzen der unmittelbaren Folgen des Klimawandels. W\u00e4hrend kleine Inseln und Staaten wie <a href=\"https:\/\/de.wikipedia.org\/wiki\/Bangladesch\">Bangladesch<\/a> mit einem Anstieg des Meeresspiegels zu k\u00e4mpfen haben, oder h\u00f6here Wassertemperaturen zu st\u00e4rkeren St\u00fcrmen f\u00fchren, profitieren andere von eisfreien H\u00e4fen und Schiffsrouten im Nordpolarmeer. Es sind die Chinesen und die Russen, die der Nordostpassage ihre Aufmerksamkeit zuwenden.<\/p>\n<p style=\"text-align: justify;\">Laut <a href=\"https:\/\/de.sputniknews.com\/wirtschaft\/20190427324808843-nordostpassage-maritime-seidenstrasse\/\">Sputnik <\/a>erkl\u00e4rte der russische Pr\u00e4sident Wladimir Putin bei einem Forum in Chinas Hauptstadt Peking: \u201eWir erw\u00e4gen die M\u00f6glichkeit ihrer (Nordostpassage) Verbindung mit der chinesischen maritimen Seidenstra\u00dfe. Dadurch soll eine globale und konkurrenzf\u00e4hige Route geschaffen werden, die das nord\u00f6stliche, \u00f6stliche und s\u00fcd\u00f6stliche Asien mit Europa verbinden wird.\u201c<\/p>\n<p style=\"text-align: justify;\">Der neue Seeweg, der dem Suezkanal sein Monopol nimmt, ist um vieles k\u00fcrzer und macht den Import chinesischer Waren billiger f\u00fcr den Handel in Europa. Doch wenn sich dieser Handelsweg lohnen soll, dann muss Europa seine Produkte genauso g\u00fcnstig nach Fernost verschiffen. Eine ausgeglichene Handelsbilanz und nicht nur m\u00f6glichst hohe Profite f\u00fcr die eigene Oligarchie, m\u00fcsste von den Regierungschefs weltweit ausgehandelt werden. Eine maritime Seidenstra\u00dfe an der russischen K\u00fcste im Nordpolarmeer entlang lohnt sich nur, wenn die Menschen in Europa Geld in der Tasche haben, um die Waren kaufen zu k\u00f6nnen. Doch das ist wieder ein anderes Thema, auch wenn alles zusammenh\u00e4ngt.<\/p>\n<p style=\"text-align: justify;\">Desweiteren sind Russen, Kanadier, US-Amerikaner und Norweger auch dabei in den jetzt eisfreien Gebieten die \u00d6l- und Gasvorkommen st\u00e4rker auszubeuten. Neue Projekte sollen noch mehr fossile Energietr\u00e4ger f\u00f6rdern, die unsere Atmosph\u00e4re weiter aufheizen und so das Problem f\u00fcr all die unwichtigen Inseln und K\u00fcstenregionen verschlimmern. Das die Konzerne, die ohne R\u00fccksicht auf die Umwelt, die Tiere, die Menschen und das Leben an sich auch noch den letzten Tropfen \u00d6l aus den Tiefen der Erde holen und Staaten, Regierungen und Menschen die ihnen nicht das geben was sie wollen mit Krieg \u00fcberziehen, auch Medien und gekaufte \u201eWissenschaftler\u201c nutzen, um Zweifel an Klimawandel, Umweltverschmutzung und Ausbeutung der Ressourcen zu streuen, sollte keinen wundern. Verschw\u00f6rungen gibt es viele, es fragt sich blo\u00df welche wirklich wahr sind und wer oder was dahinter steckt. Wie Anfangs erw\u00e4hnt: <i>\u201eCui bono?\u201c<\/i><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ffffff;\">.<\/span><br \/>\nErstver\u00f6ffentlichung am 21. Mai 2019 in unserer Partnerzeitung <a href=\"http:\/\/www.Info-Welt.eu\" target=\"_blank\" rel=\"noopener noreferrer\">INFO-WELT<\/a>. Bild und Bildunterschrift teilweise oder ganz hinzugef\u00fcgt von der Redaktion <\/span><a href=\"http:\/\/www.AmericanRebel.de\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size: 10pt;\">AmericanRebel<\/span><\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-size: 10pt;\"><a href=\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/?cat=122\" target=\"_blank\" rel=\"noopener noreferrer\">Weitere Artikel von Rui Filipe Gutschmidt<\/a> <\/span><\/p>\n<blockquote>\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt; color: #000000;\">F\u00fcr den Inhalt dieses Artikels ist der Autor bzw. die Autorin verantwortlich.<br \/>\nDabei muss es sich nicht grunds\u00e4tzlich um die Meinung der Redaktion handeln.<\/span><\/p>\n<table width=\"100%\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<form action=\"https:\/\/www.paypal.com\/cgi-bin\/webscr\" method=\"post\" target=\"_top\"><input alt=\"Jetzt einfach, schnell und sicher online bezahlen \u2013 mit PayPal.\" name=\"submit\" src=\"https:\/\/www.paypalobjects.com\/de_DE\/DE\/i\/btn\/btn_donateCC_LG.gif\" type=\"image\" \/><\/form>\n<\/td>\n<td><span style=\"color: #993300;\"><strong>Auch linker Journalismus ist nicht kostenlos<br \/>\nund auch kleine Spenden k\u00f6nnen helfen Gro\u00dfes zu ver\u00f6ffentlichen!<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"margin-left: 10px;\"><a title=\"zur Startseite\" href=\"http:\/\/www.americanrebel.de\/\"><img loading=\"lazy\" class=\"alignleft\" src=\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2017\/03\/back_ar.png\" alt=\"zur\u00fcck zur Startseite\" width=\"156\" height=\"15\" \/><\/a><\/div>\n<div style=\"margin-right: 10px;\"><a href=\"https:\/\/www.facebook.com\/groups\/1683837971860223\/permalink\/1987214344855916\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignright\" src=\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2017\/03\/ar_zu_fb.png\" alt=\"hier geht es zur Facebook Diskussionsgruppe\" width=\"353\" height=\"15\" \/><\/a><\/div>\n<p style=\"text-align: center;\"><a href=\"#respond\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"aligncenter\" src=\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2017\/03\/ar_kommentar-1.png\" alt=\"Sag uns deine Meinung zum Artikel mit einem Kommentar\/Leserbrief\" width=\"627\" height=\"20\" \/><\/a><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Rui Filipe Gutschmidt Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute Viele wollen den schnellen Klimawandel nicht wahrhaben oder den Einfluss des Menschen kleinreden. Es ist nicht weiter verwunderlich, denn die Rohstoff- und Energiemafia verdient Milliarden [&hellip;]<a class=\"more-link\" href=\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/\">&darr; Lese den Rest von diesem Eintrag&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>- Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute &ndash; Onlinezeitung AmericanRebel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute &ndash; Onlinezeitung AmericanRebel\" \/>\n<meta property=\"og:description\" content=\"Rui Filipe Gutschmidt Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute Viele wollen den schnellen Klimawandel nicht wahrhaben oder den Einfluss des Menschen kleinreden. Es ist nicht weiter verwunderlich, denn die Rohstoff- und Energiemafia verdient Milliarden [&hellip;]&darr; Lese den Rest von diesem Eintrag...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/\" \/>\n<meta property=\"og:site_name\" content=\"Onlinezeitung AmericanRebel\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-21T09:21:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-21T09:32:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2019\/05\/kuiz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"387\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/#website\",\"url\":\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/\",\"name\":\"Onlinezeitung AmericanRebel\",\"description\":\"Internationale Onlinezeitung f\\u00fcr Frieden, Humanismus, V\\u00f6lkerverst\\u00e4ndigung und Kultur\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2019\/05\/kuiz.jpg\",\"contentUrl\":\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2019\/05\/kuiz.jpg\",\"width\":630,\"height\":387,\"caption\":\"Nordostpassage-NASA - Wikipedia Commons CC 0\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/#webpage\",\"url\":\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/\",\"name\":\"- Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute &ndash; Onlinezeitung AmericanRebel\",\"isPartOf\":{\"@id\":\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/#primaryimage\"},\"datePublished\":\"2019-05-21T09:21:25+00:00\",\"dateModified\":\"2019-05-21T09:32:38+00:00\",\"author\":{\"@id\":\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/#\/schema\/person\/9edfca7917cd10b75edaae51c6e7935a\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8211; Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/#\/schema\/person\/9edfca7917cd10b75edaae51c6e7935a\",\"name\":\"Redaktion\",\"url\":\"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/author\/redaktion\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute &ndash; Onlinezeitung AmericanRebel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/","og_locale":"de_DE","og_type":"article","og_title":"- Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute &ndash; Onlinezeitung AmericanRebel","og_description":"Rui Filipe Gutschmidt Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute Viele wollen den schnellen Klimawandel nicht wahrhaben oder den Einfluss des Menschen kleinreden. Es ist nicht weiter verwunderlich, denn die Rohstoff- und Energiemafia verdient Milliarden [&hellip;]&darr; Lese den Rest von diesem Eintrag...","og_url":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/","og_site_name":"Onlinezeitung AmericanRebel","article_published_time":"2019-05-21T09:21:25+00:00","article_modified_time":"2019-05-21T09:32:38+00:00","og_image":[{"width":630,"height":387,"url":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2019\/05\/kuiz.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/#website","url":"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/","name":"Onlinezeitung AmericanRebel","description":"Internationale Onlinezeitung f\u00fcr Frieden, Humanismus, V\u00f6lkerverst\u00e4ndigung und Kultur","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/#primaryimage","inLanguage":"de","url":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2019\/05\/kuiz.jpg","contentUrl":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-content\/uploads\/2019\/05\/kuiz.jpg","width":630,"height":387,"caption":"Nordostpassage-NASA - Wikipedia Commons CC 0"},{"@type":"WebPage","@id":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/#webpage","url":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/","name":"- Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute &ndash; Onlinezeitung AmericanRebel","isPartOf":{"@id":"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/#primaryimage"},"datePublished":"2019-05-21T09:21:25+00:00","dateModified":"2019-05-21T09:32:38+00:00","author":{"@id":"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/#\/schema\/person\/9edfca7917cd10b75edaae51c6e7935a"},"breadcrumb":{"@id":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/2019\/05\/21\/ist-der-klimawandel-gewollt-china-und-russland-wollen-eisfreies-nordmeer-als-handelsroute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/"},{"@type":"ListItem","position":2,"name":"&#8211; Ist der Klimawandel gewollt? China und Russland wollen eisfreies Nordmeer als Handelsroute"}]},{"@type":"Person","@id":"http:\/\/www.deanreed.de\/AmericanRebel\/2017\/#\/schema\/person\/9edfca7917cd10b75edaae51c6e7935a","name":"Redaktion","url":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/author\/redaktion\/"}]}},"_links":{"self":[{"href":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-json\/wp\/v2\/posts\/20423"}],"collection":[{"href":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-json\/wp\/v2\/comments?post=20423"}],"version-history":[{"count":4,"href":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-json\/wp\/v2\/posts\/20423\/revisions"}],"predecessor-version":[{"id":20428,"href":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-json\/wp\/v2\/posts\/20423\/revisions\/20428"}],"wp:attachment":[{"href":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-json\/wp\/v2\/media?parent=20423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-json\/wp\/v2\/categories?post=20423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deanreed.de\/AmericanRebel\/2017\/wp-json\/wp\/v2\/tags?post=20423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}